{"id":163,"count":1,"description":"","link":"https:\/\/coupons.pizza\/blog\/tag\/calories-in-pizza\/","name":"calories in pizza","slug":"calories-in-pizza","taxonomy":"post_tag","meta":[],"yoast_head":"\n<title>calories in pizza &#8211; Slice the Price<\/title>\n<meta name=\"description\" content=\"Discover helpful tips, insights, and updates about calories in pizza. Stay informed with our latest posts, crafted especially for pizza lovers.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/coupons.pizza\/blog\/tag\/calories-in-pizza\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"calories in pizza &#8211; Slice the Price\" \/>\n<meta property=\"og:description\" content=\"Discover helpful tips, insights, and updates about calories in pizza. Stay informed with our latest posts, crafted especially for pizza lovers.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coupons.pizza\/blog\/tag\/calories-in-pizza\/\" \/>\n<meta property=\"og:site_name\" content=\"Slice the Price\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n","yoast_head_json":{"title":"calories in pizza &#8211; Slice the Price","description":"Discover helpful tips, insights, and updates about calories in pizza. Stay informed with our latest posts, crafted especially for pizza lovers.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/coupons.pizza\/blog\/tag\/calories-in-pizza\/","og_locale":"en_US","og_type":"article","og_title":"calories in pizza &#8211; Slice the Price","og_description":"Discover helpful tips, insights, and updates about calories in pizza. Stay informed with our latest posts, crafted especially for pizza lovers.","og_url":"https:\/\/coupons.pizza\/blog\/tag\/calories-in-pizza\/","og_site_name":"Slice the Price","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/coupons.pizza\/blog\/tag\/calories-in-pizza\/","url":"https:\/\/coupons.pizza\/blog\/tag\/calories-in-pizza\/","name":"calories in pizza &#8211; Slice the Price","isPartOf":{"@id":"https:\/\/coupons.pizza\/blog\/#website"},"description":"Discover helpful tips, insights, and updates about calories in pizza. Stay informed with our latest posts, crafted especially for pizza lovers.","breadcrumb":{"@id":"https:\/\/coupons.pizza\/blog\/tag\/calories-in-pizza\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/coupons.pizza\/blog\/tag\/calories-in-pizza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/coupons.pizza\/blog\/"},{"@type":"ListItem","position":2,"name":"calories in pizza"}]},{"@type":"WebSite","@id":"https:\/\/coupons.pizza\/blog\/#website","url":"https:\/\/coupons.pizza\/blog\/","name":"Coupon Pizza","description":"#1 Source of Pizza deals, coupons &amp; News","publisher":{"@id":"https:\/\/coupons.pizza\/blog\/#organization"},"alternateName":"Coupon Pizza","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coupons.pizza\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/coupons.pizza\/blog\/#organization","name":"Coupon pizza","alternateName":"Coupon Pizza","url":"https:\/\/coupons.pizza\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/coupons.pizza\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/coupons.pizza\/blog\/wp-content\/uploads\/2021\/03\/logo.png","contentUrl":"https:\/\/coupons.pizza\/blog\/wp-content\/uploads\/2021\/03\/logo.png","width":220,"height":62,"caption":"Coupon pizza"},"image":{"@id":"https:\/\/coupons.pizza\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/coupons.pizza\/blog\/wp-json\/wp\/v2\/tags\/163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coupons.pizza\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/coupons.pizza\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/coupons.pizza\/blog\/wp-json\/wp\/v2\/posts?tags=163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<!-- This website is optimized by Airlift. Learn more: https://airlift.net. Template:. Learn more: https://airlift.net. Template: 6948d1151906362cdc78c6a2. Config Timestamp: 2025-12-22 05:03:14 UTC, Cached Timestamp: 2026-09-02 15:43:28 UTC -->